{"id":23271,"date":"2019-05-15T19:33:42","date_gmt":"2019-05-15T22:33:42","guid":{"rendered":"http:\/\/infoeconomico.com.br\/portal\/pec-que-impede-executivo-de-alterar-ipi-livremente-vai-para-ultima-discussao\/"},"modified":"2019-05-15T19:33:42","modified_gmt":"2019-05-15T22:33:42","slug":"pec-que-impede-executivo-de-alterar-ipi-livremente-vai-para-ultima-discussao","status":"publish","type":"post","link":"https:\/\/infoeconomico.com.br\/portal\/pec-que-impede-executivo-de-alterar-ipi-livremente-vai-para-ultima-discussao\/","title":{"rendered":"PEC que impede Executivo de alterar IPI livremente vai para \u00faltima discuss\u00e3o"},"content":{"rendered":"<p>Duas propostas de emenda \u00e0 Constitui\u00e7\u00e3o passaram por mais uma sess\u00e3o de discuss\u00e3o em Plen\u00e1rio nesta quarta-feira (15). Pela quarta sess\u00e3o, passou a <a class=\"external-link\" href=\"http:\/\/www25.senado.leg.br\/web\/atividade\/materias\/-\/materia\/121220\">PEC 55\/2015<\/a>, que impede a Uni\u00e3o de aumentar ou reduzir, livremente, as al\u00edquotas do Imposto sobre Produtos Industrializados (IPI).<\/p>\n<p>A proposta estabelece que qualquer altera\u00e7\u00e3o do Executivo federal na al\u00edquota do tributo deve ser submetida antes ao Senado. Assim, a medida s\u00f3 passaria a valer se aprovada por maioria absoluta dos senadores. O texto tamb\u00e9m exige que estados, o Distrito Federal e munic\u00edpios sejam compensados financeiramente pela Uni\u00e3o caso haja redu\u00e7\u00e3o na arrecada\u00e7\u00e3o do IPI. Isso porque o IPI \u00e9 uma das fontes para os fundos de participa\u00e7\u00e3o dos estados e dos munic\u00edpios.<\/p>\n<p>A proposta, do senador Tasso Jereissati (PSDB-CE), foi aprovada na Comiss\u00e3o de Constitui\u00e7\u00e3o, Justi\u00e7a e Cidadania (CCJ), com relat\u00f3rio favor\u00e1vel do senador Antonio Anastasia (PSDB-MG). Na quinta e \u00faltima sess\u00e3o de discuss\u00e3o a PEC poder\u00e1 ser votada em primeiro turno.<\/p>\n<h3><strong>Avalia\u00e7\u00e3o de pol\u00edtica p\u00fablica<\/strong><\/h3>\n<p>J\u00e1 a <a class=\"external-link\" href=\"http:\/\/www25.senado.leg.br\/web\/atividade\/materias\/-\/materia\/129887\">PEC 26\/2017<\/a> passou pela segunda sess\u00e3o de discuss\u00e3o em primeiro turno. A proposta estabelece que os poderes Executivo, Legislativo e Judici\u00e1rio poder\u00e3o contar com um sistema de avalia\u00e7\u00e3o de pol\u00edticas p\u00fablicas.<\/p>\n<p>A proposi\u00e7\u00e3o estabelece que os Tr\u00eas Poderes manter\u00e3o um sistema integrado de avalia\u00e7\u00e3o com o objetivo de promover o aperfei\u00e7oamento da gest\u00e3o p\u00fablica, que avaliar\u00e1 a economicidade, a efetividade, a efic\u00e1cia e a efici\u00eancia das a\u00e7\u00f5es governamentais. O sistema dar\u00e1 subs\u00eddios t\u00e9cnicos \u00e0 formula\u00e7\u00e3o de novas pol\u00edticas p\u00fablicas, observando o princ\u00edpio da periodicidade, e ser\u00e1 exercido com o aux\u00edlio do Tribunal de Contas da Uni\u00e3o (TCU) e dos \u00f3rg\u00e3os integrantes do sistema de controle interno de cada poder.<\/p>\n<p>A proposi\u00e7\u00e3o \u00e9 da senadora Maria do Carmo Alves (DEM-SE) e tamb\u00e9m foi aprovada na CCJ, com relat\u00f3rio elaborado pelo senador Antonio Anastasia. Em vez de acrescentar um artigo \u00e0 Constitui\u00e7\u00e3o (art. 75-A), o relator sugeriu a modifica\u00e7\u00e3o dos artigos 71 e 74, que tratam sobre o controle na administra\u00e7\u00e3o p\u00fablica.<\/p>\n<h3><strong>Tramita\u00e7\u00e3o<\/strong><\/h3>\n<p>Toda PEC tem que ser votada em dois turnos no Plen\u00e1rio do Senado. Antes da vota\u00e7\u00e3o em primeiro turno, a proposta tem de ser discutida em cinco sess\u00f5es plen\u00e1rias. Ap\u00f3s aprova\u00e7\u00e3o em primeiro turno, a PEC \u00e9 discutida por mais tr\u00eas sess\u00f5es para ser votada em segundo turno, quando \u00e9 encerrado o processo legislativo na Casa onde for aprovada ou rejeitada.<\/p>\n<p>Fonte: Senado Noticias Gerais<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Duas propostas de emenda \u00e0 Constitui\u00e7\u00e3o passaram por mais uma sess\u00e3o de discuss\u00e3o em Plen\u00e1rio nesta quarta-feira (15). Pela quarta sess\u00e3o, passou a PEC 55\/2015, que impede a Uni\u00e3o de aumentar ou reduzir, livremente, as al\u00edquotas do Imposto sobre Produtos Industrializados (IPI). A proposta estabelece que qualquer altera\u00e7\u00e3o do Executivo federal na al\u00edquota do tributo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[42],"tags":[43],"class_list":["post-23271","post","type-post","status-publish","format-standard","hentry","category-central-noticias","tag-infoeconomico-news"],"_links":{"self":[{"href":"https:\/\/infoeconomico.com.br\/portal\/wp-json\/wp\/v2\/posts\/23271","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infoeconomico.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infoeconomico.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infoeconomico.com.br\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/infoeconomico.com.br\/portal\/wp-json\/wp\/v2\/comments?post=23271"}],"version-history":[{"count":0,"href":"https:\/\/infoeconomico.com.br\/portal\/wp-json\/wp\/v2\/posts\/23271\/revisions"}],"wp:attachment":[{"href":"https:\/\/infoeconomico.com.br\/portal\/wp-json\/wp\/v2\/media?parent=23271"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infoeconomico.com.br\/portal\/wp-json\/wp\/v2\/categories?post=23271"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infoeconomico.com.br\/portal\/wp-json\/wp\/v2\/tags?post=23271"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}