{"id":20487,"date":"2019-03-25T07:36:30","date_gmt":"2019-03-25T10:36:30","guid":{"rendered":"http:\/\/infoeconomico.com.br\/portal\/pi-governador-anuncia-compromissos-publicos-ele-recebe-empresario\/"},"modified":"2019-03-25T07:36:30","modified_gmt":"2019-03-25T10:36:30","slug":"pi-governador-anuncia-compromissos-publicos-ele-recebe-empresario","status":"publish","type":"post","link":"https:\/\/infoeconomico.com.br\/portal\/pi-governador-anuncia-compromissos-publicos-ele-recebe-empresario\/","title":{"rendered":"PI: governador anuncia compromissos p\u00fablicos; ele recebe empres\u00e1rio"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/www.politicareal.com.br\/uploads\/noticias\/1b56041077debcda297c963f62cad77b.jpg\"><br \/> A Pol&iacute;tica Real sempre que tem acesso publica agenda dos governadores do Nordeste<br \/>\nFonte: Pol\u00edtica Real<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Pol&iacute;tica Real sempre que tem acesso publica agenda dos governadores do Nordeste Fonte: Pol\u00edtica Real<\/p>\n","protected":false},"author":1,"featured_media":20488,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[42],"tags":[43],"class_list":["post-20487","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-central-noticias","tag-infoeconomico-news"],"_links":{"self":[{"href":"https:\/\/infoeconomico.com.br\/portal\/wp-json\/wp\/v2\/posts\/20487","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infoeconomico.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infoeconomico.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infoeconomico.com.br\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/infoeconomico.com.br\/portal\/wp-json\/wp\/v2\/comments?post=20487"}],"version-history":[{"count":0,"href":"https:\/\/infoeconomico.com.br\/portal\/wp-json\/wp\/v2\/posts\/20487\/revisions"}],"wp:attachment":[{"href":"https:\/\/infoeconomico.com.br\/portal\/wp-json\/wp\/v2\/media?parent=20487"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infoeconomico.com.br\/portal\/wp-json\/wp\/v2\/categories?post=20487"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infoeconomico.com.br\/portal\/wp-json\/wp\/v2\/tags?post=20487"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}